


{"id":1646,"count":18,"description":"","link":"https:\/\/www.voxelgroup.net\/blog\/category\/casos-de-exito\/","name":"Casos de \u00e9xito","slug":"casos-de-exito","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Casos de \u00e9xito archivos - Voxel - Blog<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casos de \u00e9xito archivos - Voxel - Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.voxelgroup.net\/blog\/category\/casos-de-exito\/\" \/>\n<meta property=\"og:site_name\" content=\"Voxel - Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.voxelgroup.net\\\/blog\\\/category\\\/casos-de-exito\\\/\",\"url\":\"https:\\\/\\\/www.voxelgroup.net\\\/blog\\\/category\\\/casos-de-exito\\\/\",\"name\":\"Casos de \u00e9xito archivos - Voxel - Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.voxelgroup.net\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.voxelgroup.net\\\/blog\\\/category\\\/casos-de-exito\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.voxelgroup.net\\\/blog\\\/category\\\/casos-de-exito\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.voxelgroup.net\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Casos de \u00e9xito\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.voxelgroup.net\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.voxelgroup.net\\\/blog\\\/\",\"name\":\"Voxel - Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.voxelgroup.net\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.voxelgroup.net\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.voxelgroup.net\\\/blog\\\/#organization\",\"name\":\"Voxel - Blog\",\"url\":\"https:\\\/\\\/www.voxelgroup.net\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.voxelgroup.net\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.voxelgroup.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/logo_Voxel_New_Positive_claim_def.webp\",\"contentUrl\":\"https:\\\/\\\/www.voxelgroup.net\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/logo_Voxel_New_Positive_claim_def.webp\",\"width\":912,\"height\":419,\"caption\":\"Voxel - Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.voxelgroup.net\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Casos de \u00e9xito archivos - Voxel - Blog","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Casos de \u00e9xito archivos - Voxel - Blog","og_url":"https:\/\/www.voxelgroup.net\/blog\/category\/casos-de-exito\/","og_site_name":"Voxel - Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.voxelgroup.net\/blog\/category\/casos-de-exito\/","url":"https:\/\/www.voxelgroup.net\/blog\/category\/casos-de-exito\/","name":"Casos de \u00e9xito archivos - Voxel - Blog","isPartOf":{"@id":"https:\/\/www.voxelgroup.net\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.voxelgroup.net\/blog\/category\/casos-de-exito\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.voxelgroup.net\/blog\/category\/casos-de-exito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.voxelgroup.net\/blog\/"},{"@type":"ListItem","position":2,"name":"Casos de \u00e9xito"}]},{"@type":"WebSite","@id":"https:\/\/www.voxelgroup.net\/blog\/#website","url":"https:\/\/www.voxelgroup.net\/blog\/","name":"Voxel - Blog","description":"","publisher":{"@id":"https:\/\/www.voxelgroup.net\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.voxelgroup.net\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.voxelgroup.net\/blog\/#organization","name":"Voxel - Blog","url":"https:\/\/www.voxelgroup.net\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.voxelgroup.net\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.voxelgroup.net\/blog\/wp-content\/uploads\/2024\/06\/logo_Voxel_New_Positive_claim_def.webp","contentUrl":"https:\/\/www.voxelgroup.net\/blog\/wp-content\/uploads\/2024\/06\/logo_Voxel_New_Positive_claim_def.webp","width":912,"height":419,"caption":"Voxel - Blog"},"image":{"@id":"https:\/\/www.voxelgroup.net\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.voxelgroup.net\/blog\/wp-json\/wp\/v2\/categories\/1646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.voxelgroup.net\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.voxelgroup.net\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.voxelgroup.net\/blog\/wp-json\/wp\/v2\/posts?categories=1646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}